{"id":52,"date":"2017-03-13T15:20:13","date_gmt":"2017-03-13T15:20:13","guid":{"rendered":"http:\/\/sw-themes.com\/porto_dummy\/?post_type=portfolio&#038;p=52"},"modified":"2025-04-09T05:04:08","modified_gmt":"2025-04-09T05:04:08","slug":"food","status":"publish","type":"portfolio","link":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/","title":{"rendered":"Foods"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc viverra lorem , consectetur adipiscing elit&#8230;<\/p>\n","protected":false},"featured_media":2931,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"portfolio_cat":[17],"portfolio_skills":[],"class_list":["post-52","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_cat-products"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Foods - Ella Trading<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foods - Ella Trading\" \/>\n<meta property=\"og:description\" content=\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc viverra lorem , consectetur adipiscing elit...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/\" \/>\n<meta property=\"og:site_name\" content=\"Ella Trading\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T05:04:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images-1024x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/\",\"url\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/\",\"name\":\"Foods - Ella Trading\",\"isPartOf\":{\"@id\":\"https:\/\/ellatrading.ae\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg\",\"datePublished\":\"2017-03-13T15:20:13+00:00\",\"dateModified\":\"2025-04-09T05:04:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage\",\"url\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg\",\"contentUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ellatrading.ae\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolios\",\"item\":\"https:\/\/ellatrading.ae\/index.php\/portfolio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Foods\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ellatrading.ae\/#website\",\"url\":\"https:\/\/ellatrading.ae\/\",\"name\":\"Ella Trading\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ellatrading.ae\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ellatrading.ae\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ellatrading.ae\/#organization\",\"name\":\"Ella Trading\",\"url\":\"https:\/\/ellatrading.ae\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png\",\"contentUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png\",\"width\":926,\"height\":512,\"caption\":\"Ella Trading\"},\"image\":{\"@id\":\"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foods - Ella Trading","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/","og_locale":"en_US","og_type":"article","og_title":"Foods - Ella Trading","og_description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc viverra lorem , consectetur adipiscing elit...","og_url":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/","og_site_name":"Ella Trading","article_modified_time":"2025-04-09T05:04:08+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images-1024x1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/","url":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/","name":"Foods - Ella Trading","isPartOf":{"@id":"https:\/\/ellatrading.ae\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage"},"image":{"@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage"},"thumbnailUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg","datePublished":"2017-03-13T15:20:13+00:00","dateModified":"2025-04-09T05:04:08+00:00","breadcrumb":{"@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#primaryimage","url":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg","contentUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2017\/03\/ai-images.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/ellatrading.ae\/index.php\/portfolio\/food\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ellatrading.ae\/"},{"@type":"ListItem","position":2,"name":"Portfolios","item":"https:\/\/ellatrading.ae\/index.php\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Foods"}]},{"@type":"WebSite","@id":"https:\/\/ellatrading.ae\/#website","url":"https:\/\/ellatrading.ae\/","name":"Ella Trading","description":"","publisher":{"@id":"https:\/\/ellatrading.ae\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellatrading.ae\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ellatrading.ae\/#organization","name":"Ella Trading","url":"https:\/\/ellatrading.ae\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/","url":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png","contentUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png","width":926,"height":512,"caption":"Ella Trading"},"image":{"@id":"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":1,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio\/52\/revisions"}],"predecessor-version":[{"id":2943,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio\/52\/revisions\/2943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/media\/2931"}],"wp:attachment":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio_cat?post=52"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/portfolio_skills?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}