{"id":1274,"date":"2021-06-02T14:18:57","date_gmt":"2021-06-02T14:18:57","guid":{"rendered":"http:\/\/sw-themes.com\/porto_dummy\/?post_type=member&amp;p=1274"},"modified":"2021-06-02T14:18:57","modified_gmt":"2021-06-02T14:18:57","slug":"janice-doe","status":"publish","type":"member","link":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/","title":{"rendered":"Janice Doe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc at elementum lacus. Fusce luctus urna ac mauris consequat, ac eleifend odio imperdiet. Sed euismod tempor orci, ullamcorper accumsan justo semper.<\/p>\n","protected":false},"featured_media":2424,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","member_cat":[],"class_list":["post-1274","member","type-member","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Janice Doe - Ella Trading<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Janice Doe - Ella Trading\" \/>\n<meta property=\"og:description\" content=\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc at elementum lacus. Fusce luctus urna ac mauris consequat, ac eleifend odio imperdiet. Sed euismod tempor orci, ullamcorper accumsan justo semper.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/\" \/>\n<meta property=\"og:site_name\" content=\"Ella Trading\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/\",\"url\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/\",\"name\":\"Janice Doe - Ella Trading\",\"isPartOf\":{\"@id\":\"https:\/\/ellatrading.ae\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg\",\"datePublished\":\"2021-06-02T14:18:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage\",\"url\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg\",\"contentUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg\",\"width\":392,\"height\":220},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ellatrading.ae\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Members\",\"item\":\"https:\/\/ellatrading.ae\/index.php\/member\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Janice Doe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ellatrading.ae\/#website\",\"url\":\"https:\/\/ellatrading.ae\/\",\"name\":\"Ella Trading\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ellatrading.ae\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ellatrading.ae\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ellatrading.ae\/#organization\",\"name\":\"Ella Trading\",\"url\":\"https:\/\/ellatrading.ae\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png\",\"contentUrl\":\"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png\",\"width\":926,\"height\":512,\"caption\":\"Ella Trading\"},\"image\":{\"@id\":\"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Janice Doe - Ella Trading","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/","og_locale":"en_US","og_type":"article","og_title":"Janice Doe - Ella Trading","og_description":"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Nunc at elementum lacus. Fusce luctus urna ac mauris consequat, ac eleifend odio imperdiet. Sed euismod tempor orci, ullamcorper accumsan justo semper.","og_url":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/","og_site_name":"Ella Trading","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/","url":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/","name":"Janice Doe - Ella Trading","isPartOf":{"@id":"https:\/\/ellatrading.ae\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage"},"image":{"@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage"},"thumbnailUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg","datePublished":"2021-06-02T14:18:57+00:00","breadcrumb":{"@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#primaryimage","url":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg","contentUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2021\/06\/aop-el-team-2.jpg","width":392,"height":220},{"@type":"BreadcrumbList","@id":"https:\/\/ellatrading.ae\/index.php\/member\/janice-doe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ellatrading.ae\/"},{"@type":"ListItem","position":2,"name":"Members","item":"https:\/\/ellatrading.ae\/index.php\/member\/"},{"@type":"ListItem","position":3,"name":"Janice Doe"}]},{"@type":"WebSite","@id":"https:\/\/ellatrading.ae\/#website","url":"https:\/\/ellatrading.ae\/","name":"Ella Trading","description":"","publisher":{"@id":"https:\/\/ellatrading.ae\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellatrading.ae\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ellatrading.ae\/#organization","name":"Ella Trading","url":"https:\/\/ellatrading.ae\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/","url":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png","contentUrl":"https:\/\/ellatrading.ae\/wp-content\/uploads\/2025\/04\/Ella-Trading-Whitepng.png","width":926,"height":512,"caption":"Ella Trading"},"image":{"@id":"https:\/\/ellatrading.ae\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/member\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/types\/member"}],"replies":[{"embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/comments?post=1274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/media\/2424"}],"wp:attachment":[{"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"member_cat","embeddable":true,"href":"https:\/\/ellatrading.ae\/index.php\/wp-json\/wp\/v2\/member_cat?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}